{"id":316,"date":"2020-12-23T08:13:18","date_gmt":"2020-12-23T08:13:18","guid":{"rendered":"https:\/\/demo.mysterythemes.com\/news-portal\/?page_id=316"},"modified":"2022-08-26T02:30:21","modified_gmt":"2022-08-26T02:30:21","slug":"blog","status":"publish","type":"page","link":"https:\/\/puenteinformativo.info\/index.php\/blog\/","title":{"rendered":"Resumen"},"content":{"rendered":"\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-3 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\"><div id=\"cv-list-post-layout\" class=\"block-52165fcf-0511-4f8b-be71-d2204f8e267d cv-block cv-block-list--layout-one\">    <div class=\"cv-post-wrapper cv-post--imagemargin column--one\">\r\n                        <article post-id=\"post-15647\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-left-wrap\">\r\n                        <div class=\"cv-post-thumb\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2023\/10\/08\/los-gobiernos-estatal-y-municipal-a-traves-de-la-tercera-jurisdiccion-sanitaria-la-secretaria-de-salud-municipal-el-republicano-ayuntamiento-y-control-ambi-ental-invitan-a-la-campana-gratuita-de-v-12\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2023\/10\/63451188-62d6-4405-be21-46d0baf1e32f-1.jpg\" alt=\"Los Gobiernos Estatal y Municipal a trav\u00e9s de la Tercera Jurisdicci\u00f3n Sanitaria, la Secretar\u00eda de Salud Municipal, el Republicano Ayuntamiento y Control Ambi-*ental, invitan a la Campa\u00f1a Gratuita de Vacunaci\u00f3n Antirr\u00e1bica masiva para perros y gatos\"\/><\/a>\r\n                        <\/div>\r\n                    <\/div><!-- .cv-post-left-wrap -->\r\n                    <div class=\"cv-post-right-wrap\">\r\n                        <div class=\"cv-post-cats-wrap\"><span class=\"cv-post-cat\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/category\/local\/\">LOCAL<\/a><\/span><\/div>                        <h2 class=\"cv-post-title\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2023\/10\/08\/los-gobiernos-estatal-y-municipal-a-traves-de-la-tercera-jurisdiccion-sanitaria-la-secretaria-de-salud-municipal-el-republicano-ayuntamiento-y-control-ambi-ental-invitan-a-la-campana-gratuita-de-v-12\/\" target=\"_self\">\r\n                                Los Gobiernos Estatal y Municipal a trav\u00e9s de la Tercera Jurisdicci\u00f3n Sanitaria, la Secretar\u00eda de Salud Municipal, el Republicano Ayuntamiento y Control Ambi-*ental, invitan a la Campa\u00f1a Gratuita de Vacunaci\u00f3n Antirr\u00e1bica masiva para perros y gatos                            <\/a>\r\n                        <\/h2>\r\n                        <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                            <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2023\/10\/08\/los-gobiernos-estatal-y-municipal-a-traves-de-la-tercera-jurisdiccion-sanitaria-la-secretaria-de-salud-municipal-el-republicano-ayuntamiento-y-control-ambi-ental-invitan-a-la-campana-gratuita-de-v-12\/\">8 octubre, 2023<\/a><\/span>                        <\/div>\r\n                        <div class=\"cv-post-content\" itemprop=\"description\"><\/div>                                            <\/div><!-- .cv-post-right-wrap -->\r\n                <\/article>\r\n                        <article post-id=\"post-1345\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-left-wrap\">\r\n                        <div class=\"cv-post-thumb\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/08\/31\/ayuntamiento-de-matamoros-extiende-durante-agosto-condonacion-de-recargos-del-impuesto-predial-29\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/plugins\/wp-blog-post-layouts\/includes\/assets\/images\/image.jpg\" alt=\"Ayuntamiento de Matamoros extiende durante agosto condonaci\u00f3n de recargos del Impuesto Predial\"\/><\/a>\r\n                        <\/div>\r\n                    <\/div><!-- .cv-post-left-wrap -->\r\n                    <div class=\"cv-post-right-wrap\">\r\n                        <div class=\"cv-post-cats-wrap\"><span class=\"cv-post-cat\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/category\/local\/\">LOCAL<\/a><\/span><\/div>                        <h2 class=\"cv-post-title\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/08\/31\/ayuntamiento-de-matamoros-extiende-durante-agosto-condonacion-de-recargos-del-impuesto-predial-29\/\" target=\"_self\">\r\n                                Ayuntamiento de Matamoros extiende durante agosto condonaci\u00f3n de recargos del Impuesto Predial                            <\/a>\r\n                        <\/h2>\r\n                        <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                            <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/08\/31\/ayuntamiento-de-matamoros-extiende-durante-agosto-condonacion-de-recargos-del-impuesto-predial-29\/\">31 agosto, 2022<\/a><\/span>                        <\/div>\r\n                        <div class=\"cv-post-content\" itemprop=\"description\"><\/div>                                            <\/div><!-- .cv-post-right-wrap -->\r\n                <\/article>\r\n                        <article post-id=\"post-28236\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-left-wrap\">\r\n                        <div class=\"cv-post-thumb\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/una-coalicion-de-23-fiscales-y-gobernadores-demando-este-jueves-al-gobierno-del-presidente-donald-trump\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2026\/09\/images-4.jpg\" alt=\"Una coalici\u00f3n de 23 fiscales y gobernadores demand\u00f3 este jueves al Gobierno del presidente\u00a0Donald Trump\"\/><\/a>\r\n                        <\/div>\r\n                    <\/div><!-- .cv-post-left-wrap -->\r\n                    <div class=\"cv-post-right-wrap\">\r\n                        <div class=\"cv-post-cats-wrap\"><span class=\"cv-post-cat\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/category\/internacional\/\">INTERNACIONAL<\/a><\/span><\/div>                        <h2 class=\"cv-post-title\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/una-coalicion-de-23-fiscales-y-gobernadores-demando-este-jueves-al-gobierno-del-presidente-donald-trump\/\" target=\"_self\">\r\n                                Una coalici\u00f3n de 23 fiscales y gobernadores demand\u00f3 este jueves al Gobierno del presidente\u00a0Donald Trump                            <\/a>\r\n                        <\/h2>\r\n                        <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                            <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/una-coalicion-de-23-fiscales-y-gobernadores-demando-este-jueves-al-gobierno-del-presidente-donald-trump\/\">1 septiembre, 2026<\/a><\/span>                        <\/div>\r\n                        <div class=\"cv-post-content\" itemprop=\"description\">PUENTE INFORMATIVO\/Washington, D.C. Una coalici\u00f3n de 23 fiscales y gobernadores demand\u00f3 este jueves al Gobierno&hellip;<\/div>                                            <\/div><!-- .cv-post-right-wrap -->\r\n                <\/article>\r\n                        <article post-id=\"post-28231\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-left-wrap\">\r\n                        <div class=\"cv-post-thumb\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/28231\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2026\/09\/images-3.jpg\" alt=\"Murio la segunda victima de la mujer que ataco con cuchillos en Time Square\"\/><\/a>\r\n                        <\/div>\r\n                    <\/div><!-- .cv-post-left-wrap -->\r\n                    <div class=\"cv-post-right-wrap\">\r\n                        <div class=\"cv-post-cats-wrap\"><span class=\"cv-post-cat\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/category\/internacional\/\">INTERNACIONAL<\/a><\/span><\/div>                        <h2 class=\"cv-post-title\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/28231\/\" target=\"_self\">\r\n                                Murio la segunda victima de la mujer que ataco con cuchillos en Time Square                            <\/a>\r\n                        <\/h2>\r\n                        <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                            <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/28231\/\">1 septiembre, 2026<\/a><\/span>                        <\/div>\r\n                        <div class=\"cv-post-content\" itemprop=\"description\">PUENTE INFORMATIVO\/Nueva York, NY Erin Piacenti, vicepresidente de Banco de America de 32 a\u00f1os, muri\u00f3&hellip;<\/div>                                            <\/div><!-- .cv-post-right-wrap -->\r\n                <\/article>\r\n                        <article post-id=\"post-28228\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-left-wrap\">\r\n                        <div class=\"cv-post-thumb\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/impulsan-prevencion-y-atencion-del-maltrato-animal-en-tamaulipas\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-1.41.57-PM.jpeg\" alt=\"Impulsan prevenci\u00f3n y atenci\u00f3n del maltrato animal en Tamaulipas\"\/><\/a>\r\n                        <\/div>\r\n                    <\/div><!-- .cv-post-left-wrap -->\r\n                    <div class=\"cv-post-right-wrap\">\r\n                        <div class=\"cv-post-cats-wrap\"><span class=\"cv-post-cat\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/category\/tamaulipas\/\">TAMAULIPAS<\/a><\/span><\/div>                        <h2 class=\"cv-post-title\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/impulsan-prevencion-y-atencion-del-maltrato-animal-en-tamaulipas\/\" target=\"_self\">\r\n                                Impulsan prevenci\u00f3n y atenci\u00f3n del maltrato animal en Tamaulipas                            <\/a>\r\n                        <\/h2>\r\n                        <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                            <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/impulsan-prevencion-y-atencion-del-maltrato-animal-en-tamaulipas\/\">1 septiembre, 2026<\/a><\/span>                        <\/div>\r\n                        <div class=\"cv-post-content\" itemprop=\"description\">PUENTE INFORMATIVO\/Cd Victoria Para evitar que estudiantes sean v\u00edctimas de escuelas que ofrecen servicios educativos&hellip;<\/div>                                            <\/div><!-- .cv-post-right-wrap -->\r\n                <\/article>\r\n                        <article post-id=\"post-28225\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-left-wrap\">\r\n                        <div class=\"cv-post-thumb\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/se-frustra-traspaso-de-lira-de-cruz-azul-al-as-de-monaco\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2026\/09\/images-2.jpg\" alt=\"Se frustra traspaso de Lira de Cruz Azul al As de M\u00f3naco\"\/><\/a>\r\n                        <\/div>\r\n                    <\/div><!-- .cv-post-left-wrap -->\r\n                    <div class=\"cv-post-right-wrap\">\r\n                        <div class=\"cv-post-cats-wrap\"><span class=\"cv-post-cat\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/category\/deportes\/\">DEPORTES<\/a><\/span><\/div>                        <h2 class=\"cv-post-title\">\r\n                            <a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/se-frustra-traspaso-de-lira-de-cruz-azul-al-as-de-monaco\/\" target=\"_self\">\r\n                                Se frustra traspaso de Lira de Cruz Azul al As de M\u00f3naco                            <\/a>\r\n                        <\/h2>\r\n                        <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                            <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2026\/09\/01\/se-frustra-traspaso-de-lira-de-cruz-azul-al-as-de-monaco\/\">1 septiembre, 2026<\/a><\/span>                        <\/div>\r\n                        <div class=\"cv-post-content\" itemprop=\"description\">PUENTE INFORMATIVO\/CDMX El\u00a0traspaso\u00a0del mediocampista mexicano\u00a0Erik Lira\u00a0al\u00a0AS M\u00f3naco se frustr\u00f3\u00a0al mediod\u00eda del\u00a0martes 1 de septiembre de&hellip;<\/div>                                            <\/div><!-- .cv-post-right-wrap -->\r\n                <\/article>\r\n            <\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div id=\"cv-grid-post-layout\" class=\"block-d75a7849-75fd-44f7-a50a-f97dce15ac7a cv-block cv-block-grid--layout-one\"><h2 class=\"cv-block-title align--left layout--one\"><span>Lo M\u00e1s Leido<\/span><\/h2>    <div class=\"cv-post-wrapper cv-post--imagemargin column--one\">\r\n        <\/div><\/div>\n<\/div>\n\n\n<div id=\"cv-masonry-post-layout\" class=\"block-e8f9e7d6-727b-4327-aa5f-0cd374da6de9 cv-block cv-masonry-post-layout cv-block-masonry--layout-two cv-block-grid--layout-two\"><h2 class=\"cv-block-title align--left layout--one\"><span>Notas Destacadas<\/span><\/h2>    <div class=\"cv-post-wrapper cv-post--imagemargin column--three\">\r\n                        <article post-id=\"post-740\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-thumb\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/08\/31\/presentan-a-camara-iniciativa-para-que-guardia-nacional-se-integre-a-la-sedena\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2022\/08\/guardianacional3.jpg\" alt=\"Presentan a C\u00e1mara, iniciativa para que Guardia Nacional se integre a la Sedena\"\/><\/a>\r\n                                            <\/div>\r\n                    <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                        <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/08\/31\/presentan-a-camara-iniciativa-para-que-guardia-nacional-se-integre-a-la-sedena\/\">31 agosto, 2022<\/a><\/span><span class=\"cv-post-author-name cv-post-meta-item\" itemprop=\"author\">By:<a href=\"https:\/\/puenteinformativo.info\/index.php\/author\/cesarperaltapuenteinformativo-info\/\">C\u00e9sar Peralta<\/a><\/span>                    <\/div>\r\n                    <h2 class=\"cv-post-title\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/08\/31\/presentan-a-camara-iniciativa-para-que-guardia-nacional-se-integre-a-la-sedena\/\" target=\"_self\">\r\n                            Presentan a C\u00e1mara, iniciativa para que Guardia Nacional se integre a la Sedena                        <\/a>\r\n                    <\/h2>\r\n\r\n                    <div class=\"cv-post-content\" itemprop=\"description\">Mediante su cuenta oficial de Twitter, el a\u00fan presidente de la C\u00e1mara de Diputados, tambi\u00e9n&hellip;<\/div>                                    <\/article>\r\n                        <article post-id=\"post-760\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-thumb\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/08\/31\/santiago-creel-nuevo-presidente-de-la-camara-de-diputados\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2022\/08\/Santiago-Cree.webp\" alt=\"Santiago Creel nuevo presidente de la C\u00e1mara de Diputados\"\/><\/a>\r\n                                            <\/div>\r\n                    <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                        <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/08\/31\/santiago-creel-nuevo-presidente-de-la-camara-de-diputados\/\">31 agosto, 2022<\/a><\/span><span class=\"cv-post-author-name cv-post-meta-item\" itemprop=\"author\">By:<a href=\"https:\/\/puenteinformativo.info\/index.php\/author\/cesarperaltapuenteinformativo-info\/\">C\u00e9sar Peralta<\/a><\/span>                    <\/div>\r\n                    <h2 class=\"cv-post-title\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/08\/31\/santiago-creel-nuevo-presidente-de-la-camara-de-diputados\/\" target=\"_self\">\r\n                            Santiago Creel nuevo presidente de la C\u00e1mara de Diputados                        <\/a>\r\n                    <\/h2>\r\n\r\n                    <div class=\"cv-post-content\" itemprop=\"description\">se aprob\u00f3 por 455 votos a favor, con lo que se alcanz\u00f3 la mayor\u00eda calificada&hellip;<\/div>                                    <\/article>\r\n                        <article post-id=\"post-1082\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-thumb\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/03\/g-n-en-coordinacion-con-el-cni-cenfi-detuviero-a-alejandro-n-por-matanza-de-migrantes-en-san-fernando\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2022\/09\/post_FOTO_GN_204__1___1_.jpg\" alt=\"G.N. en coordinaci\u00f3n con el CNI-CENFI detuvieron a Alejandro \u201cN\u201d por matanza de migrantes en San Fernando\"\/><\/a>\r\n                                            <\/div>\r\n                    <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                        <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/03\/g-n-en-coordinacion-con-el-cni-cenfi-detuviero-a-alejandro-n-por-matanza-de-migrantes-en-san-fernando\/\">3 septiembre, 2022<\/a><\/span><span class=\"cv-post-author-name cv-post-meta-item\" itemprop=\"author\">By:<a href=\"https:\/\/puenteinformativo.info\/index.php\/author\/cesarperaltapuenteinformativo-info\/\">C\u00e9sar Peralta<\/a><\/span>                    <\/div>\r\n                    <h2 class=\"cv-post-title\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/03\/g-n-en-coordinacion-con-el-cni-cenfi-detuviero-a-alejandro-n-por-matanza-de-migrantes-en-san-fernando\/\" target=\"_self\">\r\n                            G.N. en coordinaci\u00f3n con el CNI-CENFI detuvieron a Alejandro \u201cN\u201d por matanza de migrantes en San Fernando                        <\/a>\r\n                    <\/h2>\r\n\r\n                    <div class=\"cv-post-content\" itemprop=\"description\">En Tamaulipas, Guardia Nacional en coordinaci\u00f3n con el CNI-CENFI aprehenden a Alejandro \u201cN\u201d por participar&hellip;<\/div>                                    <\/article>\r\n                        <article post-id=\"post-1093\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-thumb\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/03\/en-n-l-guardia-nacional-localiza-trailer-con-60-mil-litros-de-destilado-de-petroleo\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2022\/09\/761b2570-2e93-4993-8a77-5bf857c68a81.jpg\" alt=\"En N.L. Guardia nacional localiza tr\u00e1iler con 60 mil litros de destilado de petr\u00f3leo\"\/><\/a>\r\n                                            <\/div>\r\n                    <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                        <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/03\/en-n-l-guardia-nacional-localiza-trailer-con-60-mil-litros-de-destilado-de-petroleo\/\">3 septiembre, 2022<\/a><\/span><span class=\"cv-post-author-name cv-post-meta-item\" itemprop=\"author\">By:<a href=\"https:\/\/puenteinformativo.info\/index.php\/author\/cesarperaltapuenteinformativo-info\/\">C\u00e9sar Peralta<\/a><\/span>                    <\/div>\r\n                    <h2 class=\"cv-post-title\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/03\/en-n-l-guardia-nacional-localiza-trailer-con-60-mil-litros-de-destilado-de-petroleo\/\" target=\"_self\">\r\n                            En N.L. Guardia nacional localiza tr\u00e1iler con 60 mil litros de destilado de petr\u00f3leo                        <\/a>\r\n                    <\/h2>\r\n\r\n                    <div class=\"cv-post-content\" itemprop=\"description\">Ubica remolque tipo tanque obstruyendo carretera Nacional Ciudad Victoria-Monterrey PUENTE INFORMATIVO\/Monterrey, NL En el marco&hellip;<\/div>                                    <\/article>\r\n                        <article post-id=\"post-1107\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-thumb\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/03\/javier-podria-afectar-la-peninsula-de-california\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2022\/09\/Captura-de-Pantalla-2022-09-03-a-las-16.09.23-750x536-1.jpg\" alt=\"Javier podr\u00eda afectar la pen\u00ednsula de California\"\/><\/a>\r\n                                            <\/div>\r\n                    <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                        <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/03\/javier-podria-afectar-la-peninsula-de-california\/\">3 septiembre, 2022<\/a><\/span><span class=\"cv-post-author-name cv-post-meta-item\" itemprop=\"author\">By:<a href=\"https:\/\/puenteinformativo.info\/index.php\/author\/cesarperaltapuenteinformativo-info\/\">C\u00e9sar Peralta<\/a><\/span>                    <\/div>\r\n                    <h2 class=\"cv-post-title\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/03\/javier-podria-afectar-la-peninsula-de-california\/\" target=\"_self\">\r\n                            Javier podr\u00eda afectar la pen\u00ednsula de California                        <\/a>\r\n                    <\/h2>\r\n\r\n                    <div class=\"cv-post-content\" itemprop=\"description\">Prevalecer\u00e1 el ambiente vespertino c\u00e1lido sobre la mayor parte de las entidades del norte y&hellip;<\/div>                                    <\/article>\r\n                        <article post-id=\"post-1485\" class=\"cv-post post-format--standard\" itemscope itemtype=\"http:\/\/schema.org\/articleBody\">\r\n                    <div class=\"cv-post-thumb\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/07\/rescate-humanitario-de-266-migrantes-detencion-de-3-connacionales-y-el-aseguramiento-de-3-tracto-camiones\/\"><img decoding=\"async\" src=\"https:\/\/puenteinformativo.info\/wp-content\/uploads\/2022\/09\/fecb829f-fac9-49a4-ac81-e8189f09f545.jpg\" alt=\"Rescate humanitario de 266 migrantes, detenci\u00f3n de 3 connacionales y el aseguramiento de 3 tracto camiones\"\/><\/a>\r\n                                            <\/div>\r\n                    <div class=\"cv-post-meta cv-meta-icon-show\">\r\n                        <span class=\"cv-post-date cv-post-meta-item\" itemprop=\"datePublished\"><a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/07\/rescate-humanitario-de-266-migrantes-detencion-de-3-connacionales-y-el-aseguramiento-de-3-tracto-camiones\/\">7 septiembre, 2022<\/a><\/span><span class=\"cv-post-author-name cv-post-meta-item\" itemprop=\"author\">By:<a href=\"https:\/\/puenteinformativo.info\/index.php\/author\/cesarperaltapuenteinformativo-info\/\">C\u00e9sar Peralta<\/a><\/span>                    <\/div>\r\n                    <h2 class=\"cv-post-title\">\r\n                        <a href=\"https:\/\/puenteinformativo.info\/index.php\/2022\/09\/07\/rescate-humanitario-de-266-migrantes-detencion-de-3-connacionales-y-el-aseguramiento-de-3-tracto-camiones\/\" target=\"_self\">\r\n                            Rescate humanitario de 266 migrantes, detenci\u00f3n de 3 connacionales y el aseguramiento de 3 tracto camiones                        <\/a>\r\n                    <\/h2>\r\n\r\n                    <div class=\"cv-post-content\" itemprop=\"description\">LA G.N. en coordinaci\u00f3n con el INM y elementos policiacos de Galeana, Nuevo Le\u00f3n realizaron&hellip;<\/div>                                    <\/article>\r\n            <\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"aioseo_notices":[],"blog_post_layout_featured_media_urls":{"thumbnail":"","full":""},"categories_names":null,"comments_number":"0","wpmagazine_modules_lite_featured_media_urls":{"thumbnail":"","cvmm-medium":"","cvmm-medium-plus":"","cvmm-portrait":"","cvmm-medium-square":"","cvmm-large":"","cvmm-small":"","full":""},"_links":{"self":[{"href":"https:\/\/puenteinformativo.info\/index.php\/wp-json\/wp\/v2\/pages\/316"}],"collection":[{"href":"https:\/\/puenteinformativo.info\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/puenteinformativo.info\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/puenteinformativo.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puenteinformativo.info\/index.php\/wp-json\/wp\/v2\/comments?post=316"}],"version-history":[{"count":8,"href":"https:\/\/puenteinformativo.info\/index.php\/wp-json\/wp\/v2\/pages\/316\/revisions"}],"predecessor-version":[{"id":663,"href":"https:\/\/puenteinformativo.info\/index.php\/wp-json\/wp\/v2\/pages\/316\/revisions\/663"}],"wp:attachment":[{"href":"https:\/\/puenteinformativo.info\/index.php\/wp-json\/wp\/v2\/media?parent=316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}